{"id":939,"date":"2021-07-14T11:31:49","date_gmt":"2021-07-14T09:31:49","guid":{"rendered":"https:\/\/www.alchimiacollection.com\/de\/?post_type=magazine&#038;p=939"},"modified":"2023-10-15T19:17:19","modified_gmt":"2023-10-15T17:17:19","slug":"osteria-piazzetta-cattedrale","status":"publish","type":"magazine","link":"https:\/\/www.alchimiacollection.com\/de\/magazin\/ristoranti-e-trattorie-in-puglia\/osteria-piazzetta-cattedrale\/","title":{"rendered":"Klein und fein"},"content":{"rendered":"<p><span style=\"font-size: 18pt\">Eines meiner Lieblingsrestaurants in Ostuni<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Eines meiner Lieblingsrestaurants in Ostuni<\/p>\n","protected":false},"featured_media":3554,"template":"","meta":{"_acf_changed":false,"footnotes":""},"categoria-magazine":[8],"class_list":["post-939","magazine","type-magazine","status-publish","has-post-thumbnail","hentry","categoria-magazine-ristoranti-e-trattorie-in-puglia"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Klein und fein | Alchimia Collection<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.alchimiacollection.com\/de\/magazin\/ristoranti-e-trattorie-in-puglia\/osteria-piazzetta-cattedrale\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Klein und fein | Alchimia Collection\" \/>\n<meta property=\"og:description\" content=\"Eines meiner Lieblingsrestaurants in Ostuni\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.alchimiacollection.com\/de\/magazin\/ristoranti-e-trattorie-in-puglia\/osteria-piazzetta-cattedrale\/\" \/>\n<meta property=\"og:site_name\" content=\"Alchimiacollection | DE\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-15T17:17:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.alchimiacollection.com\/de\/wp-content\/uploads\/sites\/4\/IMG_8975-min-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1333\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.alchimiacollection.com\/de\/magazin\/ristoranti-e-trattorie-in-puglia\/osteria-piazzetta-cattedrale\/\",\"url\":\"https:\/\/www.alchimiacollection.com\/de\/magazin\/ristoranti-e-trattorie-in-puglia\/osteria-piazzetta-cattedrale\/\",\"name\":\"Klein und fein | Alchimia Collection\",\"isPartOf\":{\"@id\":\"https:\/\/www.alchimiacollection.com\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.alchimiacollection.com\/de\/magazin\/ristoranti-e-trattorie-in-puglia\/osteria-piazzetta-cattedrale\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.alchimiacollection.com\/de\/magazin\/ristoranti-e-trattorie-in-puglia\/osteria-piazzetta-cattedrale\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.alchimiacollection.com\/de\/wp-content\/uploads\/sites\/4\/IMG_8975-min-3.jpg\",\"datePublished\":\"2021-07-14T09:31:49+00:00\",\"dateModified\":\"2023-10-15T17:17:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.alchimiacollection.com\/de\/magazin\/ristoranti-e-trattorie-in-puglia\/osteria-piazzetta-cattedrale\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.alchimiacollection.com\/de\/magazin\/ristoranti-e-trattorie-in-puglia\/osteria-piazzetta-cattedrale\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.alchimiacollection.com\/de\/magazin\/ristoranti-e-trattorie-in-puglia\/osteria-piazzetta-cattedrale\/#primaryimage\",\"url\":\"https:\/\/www.alchimiacollection.com\/de\/wp-content\/uploads\/sites\/4\/IMG_8975-min-3.jpg\",\"contentUrl\":\"https:\/\/www.alchimiacollection.com\/de\/wp-content\/uploads\/sites\/4\/IMG_8975-min-3.jpg\",\"width\":1000,\"height\":1333},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.alchimiacollection.com\/de\/magazin\/ristoranti-e-trattorie-in-puglia\/osteria-piazzetta-cattedrale\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.alchimiacollection.com\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Blog\",\"item\":\"https:\/\/www.alchimiacollection.com\/de\/magazin\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Essen\",\"item\":\"https:\/\/www.alchimiacollection.com\/de\/magazin\/ristoranti-e-trattorie-in-puglia\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Klein und fein\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.alchimiacollection.com\/de\/#website\",\"url\":\"https:\/\/www.alchimiacollection.com\/de\/\",\"name\":\"Alchimiacollection | DE\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.alchimiacollection.com\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Klein und fein | Alchimia Collection","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.alchimiacollection.com\/de\/magazin\/ristoranti-e-trattorie-in-puglia\/osteria-piazzetta-cattedrale\/","og_locale":"de_DE","og_type":"article","og_title":"Klein und fein | Alchimia Collection","og_description":"Eines meiner Lieblingsrestaurants in Ostuni","og_url":"https:\/\/www.alchimiacollection.com\/de\/magazin\/ristoranti-e-trattorie-in-puglia\/osteria-piazzetta-cattedrale\/","og_site_name":"Alchimiacollection | DE","article_modified_time":"2023-10-15T17:17:19+00:00","og_image":[{"width":1000,"height":1333,"url":"https:\/\/www.alchimiacollection.com\/de\/wp-content\/uploads\/sites\/4\/IMG_8975-min-3.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.alchimiacollection.com\/de\/magazin\/ristoranti-e-trattorie-in-puglia\/osteria-piazzetta-cattedrale\/","url":"https:\/\/www.alchimiacollection.com\/de\/magazin\/ristoranti-e-trattorie-in-puglia\/osteria-piazzetta-cattedrale\/","name":"Klein und fein | Alchimia Collection","isPartOf":{"@id":"https:\/\/www.alchimiacollection.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.alchimiacollection.com\/de\/magazin\/ristoranti-e-trattorie-in-puglia\/osteria-piazzetta-cattedrale\/#primaryimage"},"image":{"@id":"https:\/\/www.alchimiacollection.com\/de\/magazin\/ristoranti-e-trattorie-in-puglia\/osteria-piazzetta-cattedrale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.alchimiacollection.com\/de\/wp-content\/uploads\/sites\/4\/IMG_8975-min-3.jpg","datePublished":"2021-07-14T09:31:49+00:00","dateModified":"2023-10-15T17:17:19+00:00","breadcrumb":{"@id":"https:\/\/www.alchimiacollection.com\/de\/magazin\/ristoranti-e-trattorie-in-puglia\/osteria-piazzetta-cattedrale\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.alchimiacollection.com\/de\/magazin\/ristoranti-e-trattorie-in-puglia\/osteria-piazzetta-cattedrale\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.alchimiacollection.com\/de\/magazin\/ristoranti-e-trattorie-in-puglia\/osteria-piazzetta-cattedrale\/#primaryimage","url":"https:\/\/www.alchimiacollection.com\/de\/wp-content\/uploads\/sites\/4\/IMG_8975-min-3.jpg","contentUrl":"https:\/\/www.alchimiacollection.com\/de\/wp-content\/uploads\/sites\/4\/IMG_8975-min-3.jpg","width":1000,"height":1333},{"@type":"BreadcrumbList","@id":"https:\/\/www.alchimiacollection.com\/de\/magazin\/ristoranti-e-trattorie-in-puglia\/osteria-piazzetta-cattedrale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.alchimiacollection.com\/de\/"},{"@type":"ListItem","position":2,"name":"Blog","item":"https:\/\/www.alchimiacollection.com\/de\/magazin\/"},{"@type":"ListItem","position":3,"name":"Essen","item":"https:\/\/www.alchimiacollection.com\/de\/magazin\/ristoranti-e-trattorie-in-puglia\/"},{"@type":"ListItem","position":4,"name":"Klein und fein"}]},{"@type":"WebSite","@id":"https:\/\/www.alchimiacollection.com\/de\/#website","url":"https:\/\/www.alchimiacollection.com\/de\/","name":"Alchimiacollection | DE","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.alchimiacollection.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/www.alchimiacollection.com\/de\/wp-json\/wp\/v2\/magazine\/939","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.alchimiacollection.com\/de\/wp-json\/wp\/v2\/magazine"}],"about":[{"href":"https:\/\/www.alchimiacollection.com\/de\/wp-json\/wp\/v2\/types\/magazine"}],"version-history":[{"count":11,"href":"https:\/\/www.alchimiacollection.com\/de\/wp-json\/wp\/v2\/magazine\/939\/revisions"}],"predecessor-version":[{"id":4602,"href":"https:\/\/www.alchimiacollection.com\/de\/wp-json\/wp\/v2\/magazine\/939\/revisions\/4602"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.alchimiacollection.com\/de\/wp-json\/wp\/v2\/media\/3554"}],"wp:attachment":[{"href":"https:\/\/www.alchimiacollection.com\/de\/wp-json\/wp\/v2\/media?parent=939"}],"wp:term":[{"taxonomy":"categoria-magazine","embeddable":true,"href":"https:\/\/www.alchimiacollection.com\/de\/wp-json\/wp\/v2\/categoria-magazine?post=939"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}